{"id":14894,"date":"2020-05-31T12:00:18","date_gmt":"2020-05-31T10:00:18","guid":{"rendered":"https:\/\/wildlife-travel.com\/?p=14894"},"modified":"2022-06-05T18:19:09","modified_gmt":"2022-06-05T16:19:09","slug":"feldlerchen-auf-dem-tempelhofer-feld-in-berlin","status":"publish","type":"post","link":"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/","title":{"rendered":"Feldlerchen auf dem Tempelhofer Feld in Berlin"},"content":{"rendered":"<div id=\"pl-14894\"  class=\"panel-layout\" ><div id=\"pg-14894-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Feldlerchen geh\u00f6ren zu den Wiesenbr\u00fctern. Doch aufgrund der Intensivierung der Landwirtschaft haben es V\u00f6gel wie die Feldlerchen nicht mehr so leicht, einen geeigneten Brutplatz zu finden. Es gibt jedoch einen Ort in Deutschland wo die Anzahl dieser V\u00f6gel in den letzten Jahren stets zugenommen hat. Bei diesem Ort handelt es sich um das Tempelhofer Feld in Berlin.<\/strong><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\"><\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/#Das_Tempelhofer_Feld_in_Berlin\" >Das Tempelhofer Feld in Berlin<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/#Feldlerchen_auf_dem_Tempelhofer_Feld\" >Feldlerchen auf dem Tempelhofer Feld<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/#Ein_Artenportrait_Feldlerchen\" >Ein Artenportrait: Feldlerchen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/#Quellen_und_weitere_Informationen\" >Quellen und weitere Informationen<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Das_Tempelhofer_Feld_in_Berlin\"><\/span>Das Tempelhofer Feld in Berlin<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-2-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Das Tempelhofer Feld liegt im Berliner S\u00fcden im Bezirk Tempelhof-Sch\u00f6neberg. Bis 2005 wurde das Gel\u00e4nde des Tempelhofer Feldes als Flughafen genutzt. Seit dem 8. Mai 2010 ist es jedoch f\u00fcr die Bewohner Berlins ge\u00f6ffnet und zu einem beliebten Erholungsgebiet f\u00fcr die Gro\u00dfst\u00e4dter geworden. Zahlreiche Freizeitaktivit\u00e4ten wie Fahrradfahren, Skaten, Picknicken, Kite-Surfen oder spazieren gehen, aber auch das Vogelbeobachten k\u00f6nnen dort ausgelebt werden.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-3\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-3-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"3\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1.jpg\" width=\"1303\" height=\"869\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1.jpg 1303w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-272x182.jpg 272w\" sizes=\"(max-width: 1303px) 100vw, 1303px\" title=\"Feldlerchen\" alt=\"Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-4\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-4-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"4\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Ich bin sehr gerne dort. Denn auf dem Tempelhofer Feld f\u00fchle ich mich frei. Keine engen Gehwege. Keine Autos. Und keine Menschen, denen ich ausweichen muss (jedenfalls ist das meistens so). Mit einer Fl\u00e4che von etwa 300 ha umfasst das Tempelhofer Feld neben gro\u00dfen asphaltierten Bereichen - wo sich die ehemaligen Start- und Landebahnen befanden - auch ausgedehnte Wiesenfl\u00e4chen.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-5\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-5-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-5-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"5\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-2.jpg\" width=\"1294\" height=\"863\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-2.jpg 1294w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-2-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-2-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-2-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-2-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-2-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-2-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-2-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-2-272x182.jpg 272w\" sizes=\"(max-width: 1294px) 100vw, 1294px\" title=\"Feldlerchen\" alt=\"Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><div id=\"pgc-14894-5-1\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-5-1-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"6\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2.jpg\" width=\"1320\" height=\"880\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2.jpg 1320w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-272x182.jpg 272w\" sizes=\"(max-width: 1320px) 100vw, 1320px\" title=\"Feldlerchen\" alt=\"Wiese auf dem Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-6\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-6-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-6-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"7\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Das Tempelhofer Feld hat jahreszeitabh\u00e4ngige \u00d6ffnungszeiten und wird daher zwischen 6:00 Uhr und 7:30 Uhr ge\u00f6ffnet und zwischen 17:00 und 22:30 Uhr geschlossen. Im Juni und Juli hat das Tempelhofer Feld am l\u00e4ngsten ge\u00f6ffnet.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-7\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-7-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-7-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"8\" ><div class=\"panel-widget-style panel-widget-style-for-14894-7-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><span style=\"font-size: 16pt;\"><strong>Tipp:<\/strong><\/span> Auf der Webseite von <a href=\"https:\/\/gruen-berlin.de\/tempelhofer-feld\/besucherinformation\" target=\"_blank\" rel=\"nofollow noopener\">Gr\u00fcn Berlin<\/a> findest du mehr Informationen zu den \u00d6ffnungszeiten des Tempelhofer Feldes. Auch findest du dort weitere Informationen \u00fcber die verschiedenen Anfahrtsm\u00f6glichkeiten.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-14894-8\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-8-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-8-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"9\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Falls man gro\u00dfen Menschenmassen aus dem Weg gehen m\u00f6chte, empfehle ich, nicht am Wochenende oder an einem sch\u00f6nen Nachmittag im Sommer das Tempelhofer Feld zu besuchen. Denn wie weiter oben schon erw\u00e4hnt, ist das Tempelhofer Feld ein sehr beliebter Ort zur Erholung geworden.<\/p>\n<p>Neben den vielen Freizeitaktivit\u00e4ten, erf\u00e4hrt man auf dem Tempelhofer Feld auch einiges \u00fcber die Geschichte Berlins. Zum Bespiel lernt man, dass sich das einzige Konzentrationslager Berlins w\u00e4hrend des Zweiten Weltkrieges auf dem Areal des Tempelhofer Feldes befand. Auch wurde der ehemalige Flughafen beispielsweise in den Jahren 1948 und 1949 w\u00e4hrend der Berliner Blockade von den Alliierten \u00fcber eine Luftbr\u00fccke regelm\u00e4\u00dfig angeflogen, um den Westteil Berlins zu versorgen. Au\u00dferdem ist das Tempelhofer Feld eng mit der Deutschen Luftfahrtgeschichte verbunden. So wurde dort in den 20er Jahren die Deutsche Lufthansa gegr\u00fcndet. Es lohnt sich daher auch auf jeden Fall, sich den <a href=\"https:\/\/gruen-berlin.de\/tempelhofer-feld\/ueber-den-park\/geschichtspfad\" target=\"_blank\" rel=\"nofollow noopener\">Geschichtspfad<\/a> mal anzuschauen.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-9\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-9-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-9-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"10\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-2.jpg\" width=\"1305\" height=\"870\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-2.jpg 1305w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-2-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-2-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-2-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-2-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-2-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-2-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-2-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-2-272x182.jpg 272w\" sizes=\"(max-width: 1305px) 100vw, 1305px\" title=\"Feldlerchen\" alt=\"Geschichtspfad\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-10\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-10-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-10-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"11\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>In den n\u00e4chsten Abschnitten soll es jedoch nicht mehr um die Geschichte des Tempelhofer Feldes gehen, sondern um das eigentliche Thema dieses Blogbeitrages: die Feldlerchen.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-11\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-11-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-11-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"12\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2><span class=\"ez-toc-section\" id=\"Feldlerchen_auf_dem_Tempelhofer_Feld\"><\/span>Feldlerchen auf dem Tempelhofer Feld<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-12\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-12-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-12-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"13\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Die Intensivierung der Landwirtschaft. Der Einsatz von Pestiziden. Und der R\u00fcckgang der Insekten. All dies hat in den vergangenen Jahren dazu beigetragen, dass es in Deutschland immer weniger Feldlerchen gibt. Zwar wird die Feldlerche bei der <a href=\"https:\/\/www.iucnredlist.org\/species\/102998555\/132039889\" target=\"_blank\" rel=\"nofollow noopener\">IUCN<\/a> noch als \u201enicht gef\u00e4hrdet\u201c (Englisch: \u201eleast concern\u201c) gef\u00fchrt, doch scheint der aktuelle Trend nach unten zu zeigen. So wie es auch <a href=\"https:\/\/journals.plos.org\/plosone\/article?id=10.1371\/journal.pone.0185809\" target=\"_blank\" rel=\"nofollow noopener\">bei vielen Insekten<\/a> - also ihrer Nahrungsquelle - der Fall ist.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-13\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-13-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-13-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"14\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-16.jpg\" width=\"1183\" height=\"783\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-16.jpg 1183w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-16-300x199.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-16-1024x678.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-16-768x508.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-16-120x80.jpg 120w\" sizes=\"(max-width: 1183px) 100vw, 1183px\" title=\"Feldlerchen\" alt=\"Insekten\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-14\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-14-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-14-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"15\" ><div class=\"panel-widget-style panel-widget-style-for-14894-14-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><span style=\"font-size: 16pt;\"><strong>Interessant:<\/strong><\/span> Auch wenn die Feldlerche bei der IUCN als \u201enicht gef\u00e4hrdet\u201c gef\u00fchrt wird, laut der Berliner Roten Liste ist die Feldlerche <a href=\"https:\/\/www.berlin.de\/senuvk\/natur_gruen\/naturschutz\/artenschutz\/download\/rote_listen\/rote_liste_brutvoegel_witt_steiof.pdf\" target=\"_blank\" rel=\"nofollow noopener\">in Berlin<\/a> \u201egef\u00e4hrdet\u201c. Auch in der <a href=\"https:\/\/www.bfn.de\/themen\/rote-liste.html\" target=\"_blank\" rel=\"nofollow noopener\">Roten Liste Deutschlands<\/a> werden Feldlerchen mittlerweile in die Kategorie \u201egef\u00e4hrdet\u201c eingeordnet.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-14894-15\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-15-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-15-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"16\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Im Jahr 1998 wurde die Feldlerche als \u201eVogel des Jahres\u201c erkl\u00e4rt. Doch ist seitdem laut <a href=\"https:\/\/www.nabu.de\/imperia\/md\/content\/nabude\/vogelschutz\/vdj\/nabu_vdj2019_broschuere_final-web.pdf\" target=\"_blank\" rel=\"nofollow noopener\">NABU<\/a> jede vierte Feldlerche aus dem Brutbestand in Deutschland verschwunden. Das sind sehr besorgniserregende Beobachtungen. Daher wurde die Feldlerche im Jahr 2019 ein weiteres Jahr zum \u201eVogel des Jahres\u201c gek\u00fcrt. Damit soll sie als Stellvertreter f\u00fcr alle andere Feldv\u00f6gel wie u.a. den Kiebitz oder das Rebhuhn f\u00fcr mehr Aufmerksamkeit sorgen. Denn es ist notwendig, dass ihr R\u00fcckgang - und der weiterer Feldv\u00f6gel - in den Mittelpunkt der \u00d6ffentlichkeit ger\u00fcckt wird, um auf ihre Notlage hinzuweisen.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-16\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-16-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-16-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"17\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4.jpg\" width=\"1336\" height=\"891\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4.jpg 1336w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-272x182.jpg 272w\" sizes=\"(max-width: 1336px) 100vw, 1336px\" title=\"Feldlerchen\" alt=\"Feldlerchen auf dem Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-17\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-17-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-17-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"18\" ><div class=\"panel-widget-style panel-widget-style-for-14894-17-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><span style=\"font-size: 16pt;\"><strong>Interessant:<\/strong><\/span> Wusstest du, dass es etwa 100 verschiedene Arten aus der Familie der Lerchen (<em>Alaudidae<\/em>) gibt? In Europa kommen etwa 20 Lerchenarten vor, wovon sich allerdings nur drei Arten in Deutschland w\u00e4hrend der Brutsaison regelm\u00e4\u00dfig beobachten lassen. Dabei handelt es sich neben den Feldlerchen um die Hauben- und Heidellerchen.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-14894-18\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-18-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-18-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"19\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Ich muss zugeben. Auf den ersten Blick wirkt die Feldlerche eher etwas unscheinbar. Doch h\u00f6rt man erst mal ihren langanhaltenden und zwitschernd-trillernden Ges\u00e4ngen eine Weile zu, sollte sp\u00e4testens dann jeder Vogelbeobachter von den Feldlerchen hin und weg sein. Mich erinnern die Ges\u00e4nge der Feldlerche an sch\u00f6ne und warme Sommertage. Tage an denen die Welt noch in Ordnung zu sein schien.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-19\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-19-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-19-0-0\" class=\"so-panel widget widget_media_audio panel-first-child panel-last-child\" data-index=\"20\" ><audio class=\"wp-audio-shortcode\" id=\"audio-14894-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen.mp3?_=1\" \/><source type=\"audio\/mpeg\" src=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen.mp3?_=1\" \/><a href=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen.mp3\">https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen.mp3<\/a><\/audio><\/div><\/div><\/div><div id=\"pg-14894-20\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-20-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-20-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"21\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Doch die Welt ist nicht in Ordnung. Ganz im Gegenteil. Der Lebensraum der Feldlerchen und der vieler anderer V\u00f6gel (und nat\u00fcrlich auch anderer Tiere) verschwindet mehr und mehr. Umso erfreulicher ist es daher, einen Ort zu haben, wo sich die Feldlerchen scheinbar noch wohlf\u00fchlen.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-21\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-21-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-21-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"22\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-5.jpg\" width=\"1290\" height=\"860\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-5.jpg 1290w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-5-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-5-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-5-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-5-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-5-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-5-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-5-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-5-272x182.jpg 272w\" sizes=\"(max-width: 1290px) 100vw, 1290px\" title=\"Feldlerchen\" alt=\"Feldlerchen auf dem Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-22\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-22-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-22-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"23\" ><div class=\"panel-widget-style panel-widget-style-for-14894-22-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><span style=\"font-size: 16pt;\"><strong>Interessant:<\/strong> <\/span>Wusstest du, dass es sich bei Feldlerchen, die am Boden singen, h\u00f6chstwahrscheinlich um Weibchen handelt? W\u00e4hrend die Weibchen beim Singen am Boden bleiben, singen die M\u00e4nnchen bei den Feldlerchen hingegen meistens in der Luft.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-14894-23\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-23-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-23-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"24\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Die Wiesen des Tempelhofer Feldes bieten den Feldlerchen trotz der gro\u00dfen Besucheranzahlen einen noch idealen Brutplatz. Das zeigen vor allem auch die aktuellen Zahlen. Waren es <a href=\"https:\/\/gruen-berlin.de\/sites\/default\/files\/downloads\/monitoring_der_avifauna_2016.pdf\" target=\"_blank\" rel=\"nofollow noopener\">2005 nur 95 Brutv\u00f6gel<\/a> auf dem Tempelhofer Feld, so stieg die Anzahl der Feldlerchen im Jahr 2016 sogar auf bis zu 207 V\u00f6gel. Im <a href=\"https:\/\/gruen-berlin.de\/sites\/default\/files\/downloads\/avifauna_tempelhofer_feld_2018_0.pdf\" target=\"_blank\" rel=\"nofollow noopener\">Jahr 2018<\/a> gab es dann einen neuen H\u00f6chststand. Insgesamt 221 Brutv\u00f6gel konnten in dem Jahr gez\u00e4hlt werden. Auf die neuste Statistik bin ich schon gespannt.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-24\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-24-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-24-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"25\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-6.jpg\" width=\"1239\" height=\"826\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-6.jpg 1239w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-6-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-6-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-6-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-6-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-6-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-6-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-6-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-6-272x182.jpg 272w\" sizes=\"(max-width: 1239px) 100vw, 1239px\" title=\"Feldlerchen\" alt=\"Feldlerchen auf dem Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-25\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-25-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-25-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"26\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Auf dem Tempelhofer Feld sind die Feldlerchen ungef\u00e4hr von M\u00e4rz bis Oktober zu beobachten. Brutzeit ist von April bis Juli. Die Feldlerchen auf dem Tempelhofer Feld machen etwa 40% des Gesamtbestandes in Berlin aus (2005 waren es nur 20%). Neben den Feldlerchen lassen sich mit viel Gl\u00fcck auch noch weitere V\u00f6gel beobachten. Im Jahr 2018 wurden insgesamt 25 Brutvogelarten erfasst. Im Jahr 2016 waren es dagegen 22 Brutvogelarten. Aber in beiden Jahren war die Feldlerche die dominierende Art.<\/p>\n<p>Neben den Feldlerchen leben auf dem Tempelhofer Feld auch Haussperlinge, Grauammern, Stieglitze, <a href=\"https:\/\/wildlife-travel.com\/de\/die-nachtigall-in-berlin\/\" target=\"_blank\" rel=\"noopener\">Nachtigallen<\/a>, Amseln, Neunt\u00f6ter, Steinschm\u00e4tzer (linkes Foto), Stare (rechtes Foto), Dorn- und Klappergrasm\u00fccken oder Kohlmeisen.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-26\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-26-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-26-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"27\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-3.jpg\" width=\"1336\" height=\"891\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-3.jpg 1336w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-3-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-3-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-3-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-3-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-3-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-3-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-3-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-3-272x182.jpg 272w\" sizes=\"(max-width: 1336px) 100vw, 1336px\" title=\"Feldlerchen\" alt=\"Steinschm\u00e4tzer\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><div id=\"pgc-14894-26-1\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-26-1-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"28\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-1.jpg\" width=\"1302\" height=\"868\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-1.jpg 1302w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-1-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-1-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-1-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-1-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-1-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-1-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-1-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-4-1-272x182.jpg 272w\" sizes=\"(max-width: 1302px) 100vw, 1302px\" title=\"Feldlerchen\" alt=\"Feldlerchen auf dem Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-27\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-27-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-27-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"29\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Man kann auf dem Tempelhofer Feld auch noch ein paar mehr Vogelarten entdecken, aber kein Vogel tritt dort so h\u00e4ufig auf wie die Feldlerche. An manchen Orten ist sie sogar die einzige Art. Manche Vogelarten dagegen wurden auf dem Tempelhofer Feld in der Vergangenheit schon mal erfasst, aber scheinen den Ort jetzt wahrscheinlich zu meiden. Dazu geh\u00f6ren Buchfinken, Wachteln oder Grauschn\u00e4pper. Vor allem Wiesenpieper und Brachpieper scheinen schon seit l\u00e4ngerer Zeit nicht mehr auf das Tempelhofer Feld zur\u00fcckzukehren.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-28\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-28-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-28-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"30\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-7.jpg\" width=\"1336\" height=\"891\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-7.jpg 1336w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-7-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-7-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-7-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-7-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-7-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-7-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-7-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-7-272x182.jpg 272w\" sizes=\"(max-width: 1336px) 100vw, 1336px\" title=\"Feldlerchen\" alt=\"Feldlerchen auf dem Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-29\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-29-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-29-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"31\" ><div class=\"panel-widget-style panel-widget-style-for-14894-29-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><span style=\"font-size: 16pt;\"><strong>Interessant:<\/strong><\/span> Wusstest du, dass Steinschm\u00e4tzer neben B\u00fcschen auch Steinhaufen als Brutplatz nutzen? Neben den Steinhaufen, B\u00fcschen und den Wiesen als Brutplatz, br\u00fcten manche V\u00f6gel dagegen auch in B\u00e4umen und Str\u00e4uchern. Dazu z\u00e4hlen u.a. Dorn- und Klappergrasm\u00fccken. Es wird daher versucht, das Tempelhofer Feld strukturreich zu gestalten, um auch diesen Vogelarten einen Brutplatz zu schaffen, indem z.B. Steinhaufen f\u00fcr die Steinschm\u00e4tzer angelegt werden.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-14894-30\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-30-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-30-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"32\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Ein Punkt, der ganz wichtig ist erw\u00e4hnt zu werden, ist, die Feldlerchen bei ihrem Brutgesch\u00e4ft NICHT zu st\u00f6ren. Infotafeln weisen auf das Betretungsverbot hin. Denn wenn die Elternv\u00f6gel gest\u00f6rt oder verscheucht werden, kann es sein, dass sie ihre Eier oder Jungv\u00f6gel schutzlos sich selbst \u00fcberlassen.<\/p>\n<p>Daher wurden f\u00fcr die Feldlerchen auf dem Tempelhofer Feld Schutzzonen errichtet. Diese Schutzzonen sind sehr wichtig. Wahrscheinlich g\u00e4be es nicht so viele Feldlerchen auf dem Tempelhofer Feld, h\u00e4tte man diese Schutzzonen nicht errichtet. Diese Bereiche sind mit Flatterband gesperrt.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-31\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-31-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-31-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"33\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-8.jpg\" width=\"1325\" height=\"883\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-8.jpg 1325w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-8-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-8-1024x682.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-8-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-8-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-8-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-8-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-8-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-8-272x182.jpg 272w\" sizes=\"(max-width: 1325px) 100vw, 1325px\" title=\"Feldlerchen\" alt=\"Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-32\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-32-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-32-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"34\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Auch wenn die Feldlerchen den menschlichen Aktivit\u00e4ten gegen\u00fcber recht tolerant zu sein scheinen, br\u00fcten sie dennoch \u00fcberwiegend in den Schutzzonen. Die meisten Freizeitaktivit\u00e4ten vertragen sich wohl mit dem Br\u00fcten der Feldlerche auf dem Tempelhofer Feld (mit Ausnahme von Kitesurfen, Buggykiten und dem Steigen von Lenkdrachen). Liegewiesen, Grillpl\u00e4tze oder die f\u00fcr Hundeauslauf genutzten Fl\u00e4chen sind aber f\u00fcr die Feldlerchen dagegen nicht besiedelbar. Auch Fl\u00e4chen f\u00fcrs Drachensteigen werden von den Feldlerchen gemieden.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-33\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-33-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-33-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"35\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-9.jpg\" width=\"1336\" height=\"891\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-9.jpg 1336w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-9-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-9-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-9-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-9-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-9-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-9-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-9-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-9-272x182.jpg 272w\" sizes=\"(max-width: 1336px) 100vw, 1336px\" title=\"Feldlerchen\" alt=\"Feldlerchen auf dem Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-34\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-34-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-34-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"36\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Die Errichtung dieser Schutzzonen ist wohl eine Art Kompromiss zwischen Artenschutz und menschlicher Nutzung.<\/p>\n<p>Die positive Ver\u00e4nderung der Anzahl der Feldlerchen l\u00e4sst sich unter anderem auch auf die Errichtung dieser Sperrzonen zur\u00fcckf\u00fchren. Dort k\u00f6nnen die Feldlerchen in Ruhe br\u00fcten. Jedenfalls normalerweise. Das hei\u00dft, wenn sich alle an die Regeln halten. Ganz vor dem St\u00f6rungspotential einer gro\u00dfen Anzahl an Besuchern und unverantwortlichem Verhalten einiger von ihnen, sind die Feldlerchen nicht gesch\u00fctzt.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-35\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-35-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-35-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"37\" ><div class=\"panel-widget-style panel-widget-style-for-14894-35-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><span style=\"font-size: 16pt;\"><strong>Wichtig!<\/strong><\/span> Bitte halte dich an die Regeln des Tempelhofer Feldes. Die Flatterb\u00e4nder weisen darauf hin, dass das Betreten dieser Bereiche verboten ist. Trage auch du dazu bei, dass es den Feldlerchen gut geht und halte dich an diese Anweisungen!<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-14894-36\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-36-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-36-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"38\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Ich habe die Feldlerchen auf dem Tempelhofer Feld letzten Sommer mehrmals besucht. Leider habe ich an einem Morgen eine eher unsch\u00f6ne Beobachtung machen m\u00fcssen.<\/p>\n<p>Ich sa\u00df auf einem geteerten Weg inmitten des Tempelhofer Feldes und war mit meiner Kamera und den Feldlerchen, die sich hin und wieder in meine N\u00e4he trauten, besch\u00e4ftigt.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-37\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-37-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-37-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"39\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-10.jpg\" width=\"1332\" height=\"888\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-10.jpg 1332w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-10-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-10-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-10-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-10-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-10-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-10-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-10-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-10-272x182.jpg 272w\" sizes=\"(max-width: 1332px) 100vw, 1332px\" title=\"Feldlerchen\" alt=\"Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-38\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-38-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-38-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"40\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Auf einmal h\u00f6rte ich weit hinter mir eine Frau schreien. Ich hatte sie nicht verstanden. Aber als ich mich umdrehte wusste ich sofort um was es ging. Ein Mann lie\u00df seinen Hund in einer der Schutzzonen buddeln!<\/p>\n<p>Wie konnte er nur! Und wie konnte ich das nicht bemerken und ihn darauf hinweisen! Er war n\u00e4her bei mir als bei dieser Joggerin gewesen.<\/p>\n<p>Der Mann wurde jedenfalls sehr sauer. Und er schien mir uneinsichtig. Er beschimpfte die Frau mit \u201eSchei\u00df Faschisten!\u201c.<\/p>\n<p>Ich war sprachlos. Ich sa\u00df weiterhin auf dem geteerten Weg und beobachtete die Szene. Er nahm aber seinen Hund und entfernte sich von dem Gebiet. Mit Schimpfen h\u00f6rte er aber nicht auf.<\/p>\n<p>Ok. Er ging gl\u00fccklicherweise.<\/p>\n<p>Aber dennoch vermute ich, dass er nicht der Einzige ist, der seinen Hund auf dem Tempelhofer Feld auch w\u00e4hrend der Brutzeit frei laufen l\u00e4sst, obwohl Leinenpflicht besteht!<\/p>\n<p>Leider sind die Feldlerchen und andere Tiere schwer von uneinsichtigen oder zerst\u00f6rungsw\u00fctigen Menschen zu sch\u00fctzen. Anscheinend wurde auch im Kloh\u00e4uschen auf dem Tempelhofer Feld ein Rauchschwalben-Brutpaar entdeckt. Da sich ihr Nest nicht weit genug oben befand, waren sie nicht vor Vandalismus gesch\u00fctzt...<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-39\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-39-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-39-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"41\" ><div class=\"panel-widget-style panel-widget-style-for-14894-39-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><span style=\"font-size: 16pt;\"><strong>Wichtig!<\/strong> <\/span>Bitte lass deinen Hund an der Leine w\u00e4hrend der Brutzeit der Feldlerchen. Das ist nicht fair! Die V\u00f6gel sind schw\u00e4cher und k\u00f6nnen ihre Brut vor einem Hund nicht sch\u00fctzen! Au\u00dferdem besteht sowieso <a href=\"https:\/\/gruen-berlin.de\/tempelhofer-feld\/ueber-den-park\/schutzzone-der-feldlerche\" target=\"_blank\" rel=\"nofollow noopener\">Leinenpflicht<\/a>.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-14894-40\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-40-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-40-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"42\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Ich hoffe, dieses Jahr nicht nochmals so eine Erfahrung machen zu m\u00fcssen. Das n\u00e4chste Mal darf ich auch nicht wieder so sprachlos sitzen bleiben, sondern Menschen wie diese Joggerin unterst\u00fctzen!<\/p>\n<p>Zum Gl\u00fcck sind viele nicht so wie dieser Mann und es wird sehr viel getan, dass es den Feldlerchen und anderen Tieren auf dem Tempelhofer Feld gut geht.<\/p>\n<p>Zum Beispiel war es bis jetzt auf dem Tempelhofer Feld immer so, dass die Wiesen ein bis zweimal im Jahr gem\u00e4ht wurden. Das bedeutete, dass Anfang April mit Brutbeginn die Wiesen kurzrasig waren, und im Juli kniehoch oder h\u00fcfthoch. Genau so wie es den Feldlerchen gef\u00e4llt.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-41\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-41-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-41-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"43\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-11.jpg\" width=\"1336\" height=\"891\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-11.jpg 1336w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-11-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-11-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-11-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-11-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-11-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-11-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-11-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-11-272x182.jpg 272w\" sizes=\"(max-width: 1336px) 100vw, 1336px\" title=\"Feldlerchen\" alt=\"Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-42\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-42-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-42-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"44\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Jetzt werden zur St\u00e4rkung der biologischen Vielfalt seit August 2019 au\u00dferdem noch Skudden f\u00fcr die Beweidung eingesetzt. Bei den Skudden handelt es sich um eine <a href=\"https:\/\/gruen-berlin.de\/tempelhofer-feld\/beweidung-auf-dem-tempelhofer-feld-ein-pilotprojekt\" target=\"_blank\" rel=\"nofollow noopener\">vom Aussterben bedrohte Schafsrasse<\/a>. Auch wenn das jetzt erst mal nur ein Pilotprojekt ist, soll weiter beobachtet werden, wie sich die biologische Vielfalt in den n\u00e4chsten Jahren entwickelt. Die Skudden werden eingesetzt, weil mit ihnen eine schonendere Landschaftspflege erwartet wird.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-43\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-43-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-43-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"45\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-3-1.jpg\" width=\"1285\" height=\"857\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-3-1.jpg 1285w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-3-1-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-3-1-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-3-1-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-3-1-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-3-1-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-3-1-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-3-1-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-3-1-272x182.jpg 272w\" sizes=\"(max-width: 1285px) 100vw, 1285px\" title=\"Feldlerchen\" alt=\"Skudden auf dem Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-44\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-44-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-44-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"46\" ><div class=\"panel-widget-style panel-widget-style-for-14894-44-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><span style=\"font-size: 16pt;\"><strong>Interessant:<\/strong> <\/span>Das Tempelhofer Feld ist mittlerweile schon recht artenreich. So wurden beispielsweise schon 236 Bienen- und Wespenarten nachgewiesen. Man hat dort aber auch schon zahlreiche Insekten- und Spinnenarten entdeckt. Mit viel Gl\u00fcck und Geduld kann man einen der 68 dort vorkommenden Laufk\u00e4fer sehen. Bei den Spinnen wurden auf dem Tempelhofer Feld schon 112 Arten gez\u00e4hlt.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-14894-45\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-45-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-45-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"47\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2><span class=\"ez-toc-section\" id=\"Ein_Artenportrait_Feldlerchen\"><\/span>Ein Artenportrait: Feldlerchen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-46\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-46-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-46-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"48\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Die Feldlerche (<em>Alauda arvensis<\/em>) geh\u00f6rt zur Familie der Lerchen (<em>Alaudidae<\/em>) zu der auch die Haubenlerche (<em>Galerida cristata<\/em>) und die Heidelerche (<em>Lullala arborea<\/em>) z\u00e4hlen. Mit ihrem beigen bis r\u00f6tlich-braunen Gefieder sind die Feldlerchen sehr gut getarnt. Lediglich ihre feinen und dunklen Streifen an Kopf, R\u00fccken und B\u00fcrzel sorgen in ihrem Aussehen f\u00fcr etwas Abwechslung. Auff\u00e4llig ist au\u00dferdem noch ein heller und kr\u00e4ftiger \u00dcberaugenstreif.<\/p>\n<p>Ja. Die Feldlerchen sind mit ihrem tarnfarbenem Gefieder leicht zu \u00fcbersehen und nicht mit den bunten und <a href=\"https:\/\/wildlife-travel.com\/de\/einblick-in-die-vogelwelt-brasiliens-im-itatiaia-nationalpark\/\" target=\"_blank\" rel=\"noopener\">auff\u00e4lligen V\u00f6geln Brasiliens<\/a> in ihrem Aussehen zu vergleichen. Dennoch hat sie etwas an sich, das viele Vogelenthusiasten begeistert. Wie mich zum Beispiel.<\/p>\n<p>Sie ist ca. 16-18 cm gro\u00df, also etwas gr\u00f6\u00dfer als ein <a href=\"https:\/\/wildlife-travel.com\/de\/die-stunde-der-wintervoegel-voegel-zaehlen-im-januar\/\" target=\"_blank\" rel=\"noopener\">Haussperling<\/a>.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-47\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-47-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-47-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"49\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-12.jpg\" width=\"1336\" height=\"891\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-12.jpg 1336w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-12-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-12-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-12-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-12-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-12-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-12-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-12-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-12-272x182.jpg 272w\" sizes=\"(max-width: 1336px) 100vw, 1336px\" title=\"Feldlerchen\" alt=\"Feldlerchen auf dem Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-48\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-48-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-48-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"50\" ><div class=\"panel-widget-style panel-widget-style-for-14894-48-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><span style=\"font-size: 16pt;\"><strong>Interessant:<\/strong><\/span> Die Feldlerchen sind nicht mit den Haubenlerchen zu verwechseln. Aber manchmal zeigen die Feldlerchen dennoch eine kleine Federhaube, indem sie ihre Scheitelfedern zu einer kleinen Haube str\u00e4uben. Manchmal liegen die Federn aber auch einfach nur glatt auf ihrem K\u00f6pfchen.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-14894-49\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-49-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-49-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"51\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Bemerkenswert an der Feldlerche ist, dass sie ein bis drei Mal im Jahr br\u00fcten kann. Wobei anscheinend auch schon <a href=\"https:\/\/www.nabu.de\/imperia\/md\/content\/nabude\/vogelschutz\/vdj\/nabu_vdj2019_broschuere_final-web.pdf\" target=\"_blank\" rel=\"nofollow noopener\">bis zu sechs Bruten im Jahr<\/a> nachgewiesen wurden. Die Jungv\u00f6gel m\u00fcssen daher schon nach knapp drei Wochen selbstst\u00e4ndig werden. Sie sehen dann auch schon so wie die erwachsenen Feldlerchen aus.<\/p>\n<p>Warum das wohl so ist? Vielleicht liegt es ja daran, weil sie auf dem Boden br\u00fcten? Denn Weibchen der Feldlerchen suchen sich nach der Paarung einen trockenen und ebenen Platz mit wenig Vegetation auf der Wiese. Hat das damit zu tun? Weil die Feldlerchen an so einem Ort ja auch vielen R\u00e4ubern wehrlos ausgeliefert sind. Andererseits k\u00f6nnen sie auf flachen und ebenen Landschaften schnell einen Feind ersp\u00e4hen...<\/p>\n<p>Nichtsdestotrotz, die Weibchen bauen das Nest. Die M\u00e4nnchen beteiligen sich nicht beim Nestbau. Lediglich dann, wenn die Jungv\u00f6gel geschl\u00fcpft sind, hilft er dem Weibchen bei der Nahrungssuche.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-50\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-50-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-50-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"52\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-13.jpg\" width=\"1336\" height=\"891\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-13.jpg 1336w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-13-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-13-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-13-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-13-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-13-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-13-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-13-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-13-272x182.jpg 272w\" sizes=\"(max-width: 1336px) 100vw, 1336px\" title=\"Feldlerchen\" alt=\"Feldlerchen auf dem Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-51\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-51-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-51-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"53\" ><div class=\"panel-widget-style panel-widget-style-for-14894-51-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><span style=\"font-size: 16pt;\"><strong>Interessant:<\/strong> <\/span>Die Jungv\u00f6gel der Feldlerchen kommen nackt und blind zur Welt, aber schon nach 7 bis 11 Tagen verlassen die Jungv\u00f6gel zum ersten Mal das Nest. Dadurch sch\u00fctzen sie sich vor Nestr\u00e4ubern. Schon mit etwa zwei Wochen beginnen die jungen Feldlerchen mit ihren ersten Flugversuchen.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-14894-52\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-52-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-52-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"54\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Feldlerchen ern\u00e4hren sich je nach Jahreszeit entweder von Pflanzen oder kleinen Insekten und Spinnen. W\u00e4hrend sie im Winter vor allem pflanzliche Nahrung finden, stellen die Feldlerchen ihren Speiseplan im Fr\u00fchling und Sommer auf kleine Tiere um. Neben Pflanzen, Insekten und Spinnen, ern\u00e4hren sie sich auch von Regenw\u00fcrmern und kleinen Schnecken.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-53\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-53-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-53-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"55\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-14.jpg\" width=\"1336\" height=\"891\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-14.jpg 1336w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-14-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-14-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-14-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-14-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-14-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-14-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-14-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-14-272x182.jpg 272w\" sizes=\"(max-width: 1336px) 100vw, 1336px\" title=\"Feldlerchen\" alt=\"Feldlerchen auf dem Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-54\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-54-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-54-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"56\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Feldlerchen bevorzugen offene und weitl\u00e4ufige Landschaften. Wiesen und Weiden. Aber auch \u00c4cker kommen f\u00fcr die Feldlerchen als Lebensraum in Frage. Sie brauchen eine freie Sicht, damit sie ihre Raubfeinde schnell entdecken k\u00f6nnen. Daher findet man sie auch eher nicht am Waldrand oder in Hecken. Damit die Feldlerchen ihre Bodennester bauen k\u00f6nnen, darf die Vegetation allerdings auch nicht zu dicht sein.<\/p>\n<p>Feldlerchen sind Kurzstreckenzieher, wobei sie in Westeuropa das ganze Jahr \u00fcber vorkommen k\u00f6nnen. In Mitteleuropa dagegen ziehen die Feldlerchen im Herbst Richtung S\u00fcdeuropa, wo sie zum Beispiel in S\u00fcdfrankreich oder Spanien \u00fcberwintern. Im Fr\u00fchling kehren sie dann wieder zur\u00fcck.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-55\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-55-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-55-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"57\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-15.jpg\" width=\"1336\" height=\"891\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-15.jpg 1336w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-15-300x200.jpg 300w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-15-1024x683.jpg 1024w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-15-768x512.jpg 768w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-15-840x560.jpg 840w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-15-120x80.jpg 120w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-15-360x240.jpg 360w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-15-600x400.jpg 600w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-15-272x182.jpg 272w\" sizes=\"(max-width: 1336px) 100vw, 1336px\" title=\"Feldlerchen\" alt=\"Feldlerchen auf dem Tempelhofer Feld\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-56\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-56-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-56-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"58\" ><div class=\"panel-widget-style panel-widget-style-for-14894-56-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><span style=\"font-size: 16pt;\"><strong>Interessant:<\/strong><\/span> Wusstest du, dass die \u00f6stlichste Ausbreitung der Feldlerchen bis nach Japan reicht? Feldlerchen sind keineswegs nur in Europa anzutreffen. Au\u00dferdem verlagert sich ihr Verbreitungsgebiet im Winter Richtung S\u00fcden, sodass sie auch im afrikanischen Mittelmeerraum anzutreffen sind. In Neuseeland und Australien wie z.B. auf Tasmanien wurden Feldlerchen eingef\u00fchrt.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-14894-57\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-57-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-57-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"59\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Auch wenn die Feldlerche eine recht weite Verbreitung hat, gehen ihre Bestandszahlen nach unten. Grund ist vor allem die Intensivierung der Landwirtschaft. Sie hat zwar als Kulturfolger von der Ausweitung der Ackerfl\u00e4chen in der Vergangenheit profitiert, doch durch die Intensivierung der Landwirtschaft finden die Feldlerchen keinen Brutlebensraum mehr wo sie mehrmals im Jahr br\u00fcten k\u00f6nnen. Daher werden sie jetzt immer weniger. Das betrifft auch andere Vogelarten der Agrarlandschaft.<\/p>\n<p>Das Tempelhofer Feld ist somit f\u00fcr die Feldlerchen eine Art Ersatzlebensraum geworden.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-58\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-58-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-58-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"60\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2><span class=\"ez-toc-section\" id=\"Quellen_und_weitere_Informationen\"><\/span>Quellen und weitere Informationen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-59\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-59-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-59-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"61\" ><div class=\"panel-widget-style panel-widget-style-for-14894-59-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Das Tempelhofer Feld auf <a href=\"https:\/\/gruen-berlin.de\/tempelhofer-feld\" target=\"_blank\" rel=\"noopener\">Gr\u00fcn Berlin<\/a><\/p>\n<p><a href=\"https:\/\/gruen-berlin.de\/tempelhofer-feld\/ueber-den-park\/schutzzone-der-feldlerche\" target=\"_blank\" rel=\"nofollow noopener\">Schutzzonen<\/a> der Feldlerchen<\/p>\n<p>\u201eMonitoring der Avifauna des Tempelhofer Feldes in Berlin <a href=\"https:\/\/gruen-berlin.de\/sites\/default\/files\/downloads\/avifauna_tempelhofer_feld_2018_0.pdf\" target=\"_blank\" rel=\"nofollow noopener\">im Jahr 2018<\/a> und Vergleich mit den Brutvogelerfassungen 2005 und 2010 bis 2017\u201c von Rainer Altenkamp<\/p>\n<p>\u201eMonitoring der Avifauna des Tempelhofer Feldes in Berlin <a href=\"https:\/\/gruen-berlin.de\/sites\/default\/files\/downloads\/monitoring_der_avifauna_2016.pdf\" target=\"_blank\" rel=\"nofollow noopener\">im Jahr 2016<\/a> und Vergleich mit den Brutvogelerfassungen 2005 und 2010 bis 2015\u201c von Rainer Altenkamp<\/p>\n<p>Online-Brosch\u00fcre vom <a href=\"https:\/\/www.nabu.de\/imperia\/md\/content\/nabude\/vogelschutz\/vdj\/nabu_vdj2019_broschuere_final-web.pdf\" target=\"_blank\" rel=\"nofollow noopener\">NABU<\/a> \u00fcber die Feldlerchen<\/p>\n<p><a href=\"https:\/\/www.nabu.de\/tiere-und-pflanzen\/aktionen-und-projekte\/vogel-des-jahres\/index.html\" target=\"_blank\" rel=\"nofollow noopener\">Vogel des Jahres<\/a> auf der Webseite vom NABU<\/p>\n<p><a href=\"https:\/\/www.berlin.de\/senuvk\/natur_gruen\/naturschutz\/artenschutz\/de\/rote_listen\/voegel.shtml\" target=\"_blank\" rel=\"nofollow noopener\">Rote Liste<\/a> von Berlin<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-14894-60\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-60-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-60-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"62\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Warst du schon mal auf dem Tempelhofer Feld und hast Feldlerchen beobachtet? Oder hast du diese V\u00f6gel woanders gesehen? Lass es mich doch in den Kommentaren wissen.<\/strong><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-14894-61\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-14894-61-0\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-61-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"63\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-1.jpg\" width=\"800\" height=\"1200\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-1.jpg 800w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-1-200x300.jpg 200w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-1-683x1024.jpg 683w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-1-1-768x1152.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"Feldlerchen\" alt=\"Feldlerchen\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><div id=\"pgc-14894-61-1\"  class=\"panel-grid-cell\" ><div id=\"panel-14894-61-1-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"64\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-14894\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-1.jpg\" width=\"800\" height=\"1200\" srcset=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-1.jpg 800w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-1-200x300.jpg 200w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-1-683x1024.jpg 683w, https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-2-1-768x1152.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"Feldlerchen\" alt=\"Feldlerchen\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":14895,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[154],"tags":[127,156,125],"class_list":["post-14894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-germany","tag-artenschutz","tag-tiere-in-der-stadt","tag-voegel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feldlerchen auf dem Tempelhofer Feld in Berlin, Deutschland<\/title>\n<meta name=\"description\" content=\"Feldlerchen sind in Deutschland \u201egef\u00e4hrdet\u201c. Ihr Lebensraum verschwindet und sie finden weniger Brutpl\u00e4tze. Auf dem Tempelhofer Feld br\u00fcten einige.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feldlerchen auf dem Tempelhofer Feld in Berlin, Deutschland\" \/>\n<meta property=\"og:description\" content=\"Feldlerchen sind in Deutschland \u201egef\u00e4hrdet\u201c. Ihr Lebensraum verschwindet und sie finden weniger Brutpl\u00e4tze. Auf dem Tempelhofer Feld br\u00fcten einige.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-31T10:00:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-05T16:19:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"819\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tanja Heinz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tanja Heinz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\\\/\"},\"author\":{\"name\":\"Tanja Heinz\",\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/#\\\/schema\\\/person\\\/37ec276948c84f4f860abef1a19c2e62\"},\"headline\":\"Feldlerchen auf dem Tempelhofer Feld in Berlin\",\"datePublished\":\"2020-05-31T10:00:18+00:00\",\"dateModified\":\"2022-06-05T16:19:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\\\/\"},\"wordCount\":2997,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/#\\\/schema\\\/person\\\/37ec276948c84f4f860abef1a19c2e62\"},\"image\":{\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wildlife-travel.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Feldlerchen-scaled.jpg\",\"keywords\":[\"Artenschutz\",\"Tiere in der Stadt\",\"V\u00f6gel\"],\"articleSection\":[\"Germany\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\\\/\",\"url\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\\\/\",\"name\":\"Feldlerchen auf dem Tempelhofer Feld in Berlin, Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wildlife-travel.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Feldlerchen-scaled.jpg\",\"datePublished\":\"2020-05-31T10:00:18+00:00\",\"dateModified\":\"2022-06-05T16:19:09+00:00\",\"description\":\"Feldlerchen sind in Deutschland \u201egef\u00e4hrdet\u201c. Ihr Lebensraum verschwindet und sie finden weniger Brutpl\u00e4tze. Auf dem Tempelhofer Feld br\u00fcten einige.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wildlife-travel.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Feldlerchen-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/wildlife-travel.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Feldlerchen-scaled.jpg\",\"width\":2560,\"height\":819,\"caption\":\"Feldlerchen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feldlerchen auf dem Tempelhofer Feld in Berlin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/\",\"name\":\"\",\"description\":\"Wildlife Travel\",\"publisher\":{\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/#\\\/schema\\\/person\\\/37ec276948c84f4f860abef1a19c2e62\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/#\\\/schema\\\/person\\\/37ec276948c84f4f860abef1a19c2e62\",\"name\":\"Tanja Heinz\",\"logo\":{\"@id\":\"https:\\\/\\\/wildlife-travel.com\\\/de\\\/#\\\/schema\\\/person\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feldlerchen auf dem Tempelhofer Feld in Berlin, Deutschland","description":"Feldlerchen sind in Deutschland \u201egef\u00e4hrdet\u201c. Ihr Lebensraum verschwindet und sie finden weniger Brutpl\u00e4tze. Auf dem Tempelhofer Feld br\u00fcten einige.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/","og_locale":"de_DE","og_type":"article","og_title":"Feldlerchen auf dem Tempelhofer Feld in Berlin, Deutschland","og_description":"Feldlerchen sind in Deutschland \u201egef\u00e4hrdet\u201c. Ihr Lebensraum verschwindet und sie finden weniger Brutpl\u00e4tze. Auf dem Tempelhofer Feld br\u00fcten einige.","og_url":"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/","article_published_time":"2020-05-31T10:00:18+00:00","article_modified_time":"2022-06-05T16:19:09+00:00","og_image":[{"width":2560,"height":819,"url":"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-scaled.jpg","type":"image\/jpeg"}],"author":"Tanja Heinz","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tanja Heinz","Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/#article","isPartOf":{"@id":"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/"},"author":{"name":"Tanja Heinz","@id":"https:\/\/wildlife-travel.com\/de\/#\/schema\/person\/37ec276948c84f4f860abef1a19c2e62"},"headline":"Feldlerchen auf dem Tempelhofer Feld in Berlin","datePublished":"2020-05-31T10:00:18+00:00","dateModified":"2022-06-05T16:19:09+00:00","mainEntityOfPage":{"@id":"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/"},"wordCount":2997,"commentCount":0,"publisher":{"@id":"https:\/\/wildlife-travel.com\/de\/#\/schema\/person\/37ec276948c84f4f860abef1a19c2e62"},"image":{"@id":"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/#primaryimage"},"thumbnailUrl":"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-scaled.jpg","keywords":["Artenschutz","Tiere in der Stadt","V\u00f6gel"],"articleSection":["Germany"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/","url":"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/","name":"Feldlerchen auf dem Tempelhofer Feld in Berlin, Deutschland","isPartOf":{"@id":"https:\/\/wildlife-travel.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/#primaryimage"},"image":{"@id":"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/#primaryimage"},"thumbnailUrl":"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-scaled.jpg","datePublished":"2020-05-31T10:00:18+00:00","dateModified":"2022-06-05T16:19:09+00:00","description":"Feldlerchen sind in Deutschland \u201egef\u00e4hrdet\u201c. Ihr Lebensraum verschwindet und sie finden weniger Brutpl\u00e4tze. Auf dem Tempelhofer Feld br\u00fcten einige.","breadcrumb":{"@id":"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/#primaryimage","url":"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-scaled.jpg","contentUrl":"https:\/\/wildlife-travel.com\/wp-content\/uploads\/2020\/04\/Feldlerchen-scaled.jpg","width":2560,"height":819,"caption":"Feldlerchen"},{"@type":"BreadcrumbList","@id":"https:\/\/wildlife-travel.com\/de\/feldlerchen-auf-dem-tempelhofer-feld-in-berlin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wildlife-travel.com\/de\/"},{"@type":"ListItem","position":2,"name":"Feldlerchen auf dem Tempelhofer Feld in Berlin"}]},{"@type":"WebSite","@id":"https:\/\/wildlife-travel.com\/de\/#website","url":"https:\/\/wildlife-travel.com\/de\/","name":"","description":"Wildlife Travel","publisher":{"@id":"https:\/\/wildlife-travel.com\/de\/#\/schema\/person\/37ec276948c84f4f860abef1a19c2e62"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wildlife-travel.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":["Person","Organization"],"@id":"https:\/\/wildlife-travel.com\/de\/#\/schema\/person\/37ec276948c84f4f860abef1a19c2e62","name":"Tanja Heinz","logo":{"@id":"https:\/\/wildlife-travel.com\/de\/#\/schema\/person\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/wildlife-travel.com\/de\/wp-json\/wp\/v2\/posts\/14894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wildlife-travel.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wildlife-travel.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wildlife-travel.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wildlife-travel.com\/de\/wp-json\/wp\/v2\/comments?post=14894"}],"version-history":[{"count":0,"href":"https:\/\/wildlife-travel.com\/de\/wp-json\/wp\/v2\/posts\/14894\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wildlife-travel.com\/de\/wp-json\/wp\/v2\/media\/14895"}],"wp:attachment":[{"href":"https:\/\/wildlife-travel.com\/de\/wp-json\/wp\/v2\/media?parent=14894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wildlife-travel.com\/de\/wp-json\/wp\/v2\/categories?post=14894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wildlife-travel.com\/de\/wp-json\/wp\/v2\/tags?post=14894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}